{"id":6983,"date":"2025-12-01T12:38:59","date_gmt":"2025-12-01T12:38:59","guid":{"rendered":"https:\/\/mediapreparators.clickame.net\/criteres-environnementaux\/"},"modified":"2026-08-31T10:43:07","modified_gmt":"2026-08-31T10:43:07","slug":"criteres-environnementaux","status":"publish","type":"page","link":"https:\/\/www.mediapreparators.com\/fr\/criteres-environnementaux\/","title":{"rendered":"Crit\u00e8res environnementaux"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> &lt;\u00a01<\/span> <span class=\"rt-label rt-postfix\">minuto<\/span><\/span>\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6983\" class=\"elementor elementor-6983 elementor-3709\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ea31f5 e-flex e-con-boxed e-con e-parent\" data-id=\"3ea31f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-899b48e elementor-widget elementor-widget-heading\" data-id=\"899b48e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Crit\u00e8res environnementaux<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c366a2e parrafo elementor-widget elementor-widget-text-editor\" data-id=\"c366a2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"color: black;\"><strong>INFORMATIONS IMPORTANTES POUR NOS FOURNISSEURS<\/strong><\/h6><p>Notre organisation dispose d\u2019un <strong>syst\u00e8me de management environnemental certifi\u00e9 conform\u00e9ment \u00e0 la norme ISO 14001<\/strong>, qui \u00e9tablit le cadre pour la gestion et l\u2019am\u00e9lioration continue de notre performance environnementale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9adee elementor-widget elementor-widget-image\" data-id=\"6c9adee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1128\" height=\"350\" src=\"https:\/\/www.mediapreparators.com\/wp-content\/uploads\/2025\/12\/img-principal-ISO14001.jpg\" class=\"attachment-full size-full wp-image-6982\" alt=\"\" srcset=\"https:\/\/www.mediapreparators.com\/wp-content\/uploads\/2025\/12\/img-principal-ISO14001.jpg 1128w, https:\/\/www.mediapreparators.com\/wp-content\/uploads\/2025\/12\/img-principal-ISO14001-300x93.jpg 300w, https:\/\/www.mediapreparators.com\/wp-content\/uploads\/2025\/12\/img-principal-ISO14001-1024x318.jpg 1024w, https:\/\/www.mediapreparators.com\/wp-content\/uploads\/2025\/12\/img-principal-ISO14001-768x238.jpg 768w\" sizes=\"(max-width: 1128px) 100vw, 1128px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c80f9b6 parrafo elementor-widget elementor-widget-text-editor\" data-id=\"c80f9b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"color: black;\"><strong>Qu\u2019est-ce qu\u2019un syst\u00e8me de management environnemental ?<\/strong><\/h6><p>Un syst\u00e8me de gestion environnementale est un outil permettant de minimiser notre impact sur l\u2019environnement. Elle englobe non seulement nos propres activit\u00e9s, mais aussi celles des fournisseurs qui nous procurent les mat\u00e9riaux, les produits et les services dont nous avons besoin. <\/p><p>\u00c0 cet \u00e9gard, en tant que fournisseur de RAYPA, il est essentiel que vous respectiez les exigences suivantes en mati\u00e8re de gestion de l\u2019environnement :<\/p><ul><li>Respecter l\u2019ensemble de la l\u00e9gislation environnementale applicable.<\/li><li>G\u00e9rer correctement les d\u00e9chets et les \u00e9missions g\u00e9n\u00e9r\u00e9s.<\/li><li>Adopter des pratiques de consommation durable des ressources.<\/li><\/ul><h6 style=\"color: black;\"><strong>ATTENTION<\/strong><\/h6><p>Si vous disposez d\u2019un certificat de gestion environnementale, veuillez nous l\u2019envoyer par courrier \u00e9lectronique (ISO-14001, etc.).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Tiempo de lectura:<\/span> <span class=\"rt-time\"> &lt;\u00a01<\/span> <span class=\"rt-label rt-postfix\">minuto<\/span><\/span>Crit\u00e8res environnementaux INFORMATIONS IMPORTANTES POUR NOS FOURNISSEURS Notre organisation dispose d\u2019un syst\u00e8me de management environnemental certifi\u00e9 conform\u00e9ment \u00e0 la norme ISO 14001, qui \u00e9tablit le cadre pour la gestion et l\u2019am\u00e9lioration continue de notre performance environnementale. Qu\u2019est-ce qu\u2019un syst\u00e8me de management environnemental ? Un syst\u00e8me de gestion environnementale est un outil permettant de minimiser notre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6983","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/pages\/6983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/comments?post=6983"}],"version-history":[{"count":5,"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/pages\/6983\/revisions"}],"predecessor-version":[{"id":7514,"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/pages\/6983\/revisions\/7514"}],"wp:attachment":[{"href":"https:\/\/www.mediapreparators.com\/fr\/wp-json\/wp\/v2\/media?parent=6983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}